{"id":8293,"date":"2020-03-05T16:39:15","date_gmt":"2020-03-05T19:39:15","guid":{"rendered":"http:\/\/expormanequins.com.br\/site\/?post_type=product&#038;p=8293"},"modified":"2020-03-05T16:39:16","modified_gmt":"2020-03-05T19:39:16","slug":"3612","status":"publish","type":"product","link":"https:\/\/expormanequins.com.br\/site\/es\/product\/3612\/","title":{"rendered":"3612"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":8296,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[70,592],"product_tag":[],"_links":{"self":[{"href":"https:\/\/expormanequins.com.br\/site\/es\/wp-json\/wp\/v2\/product\/8293"}],"collection":[{"href":"https:\/\/expormanequins.com.br\/site\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/expormanequins.com.br\/site\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/expormanequins.com.br\/site\/es\/wp-json\/wp\/v2\/comments?post=8293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expormanequins.com.br\/site\/es\/wp-json\/wp\/v2\/media\/8296"}],"wp:attachment":[{"href":"https:\/\/expormanequins.com.br\/site\/es\/wp-json\/wp\/v2\/media?parent=8293"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/expormanequins.com.br\/site\/es\/wp-json\/wp\/v2\/product_cat?post=8293"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/expormanequins.com.br\/site\/es\/wp-json\/wp\/v2\/product_tag?post=8293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}